{"id":20097,"date":"2025-05-12T17:14:14","date_gmt":"2025-05-12T21:14:14","guid":{"rendered":"https:\/\/www.assur360.ca\/business-insurance-3-minute-quote\/hotel-insurance-get-your-personalized-quote\/"},"modified":"2026-04-12T22:51:43","modified_gmt":"2026-04-13T02:51:43","slug":"hotel-insurance-get-your-personalized-quote","status":"publish","type":"page","link":"https:\/\/www.assur360.ca\/en\/business-insurance-3-minute-quote\/hotel-insurance-get-your-personalized-quote\/","title":{"rendered":"Hotel Insurance: Get Your Personalized Quote"},"content":{"rendered":"\n<style>#ez-toc-container{display:none!important}<\/style>\n\n<div style=\"background:linear-gradient(135deg,#0d1f2d,#1a3a4a);border-radius:16px;padding:40px 36px;margin:32px auto;box-shadow:0 10px 30px rgba(13,31,45,0.18);max-width:100%;\">\n  <div style=\"display:flex;gap:32px;align-items:center;justify-content:center;flex-wrap:wrap;\">\n    <div style=\"flex:1 1 380px;min-width:280px;text-align:left;\">\n      <p style=\"color:#10c4c7;font-size:13px;font-weight:700;text-transform:uppercase;letter-spacing:3px;margin:0 0 10px;\">ENTREPRISE PAR ACTIVIT\u00c9<\/p>\n      <p style=\"color:#ffffff;font-size:28px;font-weight:800;margin:0 0 12px;line-height:1.25;font-family:inherit;\">Assurance selon votre secteur<\/p>\n      <p style=\"color:#94a3b8;font-size:16px;line-height:1.6;margin:0 0 22px;\">Restaurant, construction, commerce, services pros : protection sur mesure.<\/p>\n      <div style=\"display:flex;gap:10px;flex-wrap:wrap;\">\n        <a href=\"\/?page_id=17197\" style=\"background:#10c4c7;color:#0d1f2d;padding:14px 26px;border-radius:8px;font-weight:700;text-decoration:none;font-size:15px;display:inline-block;\">Soumission entreprise<\/a>\n        <a href=\"tel:+18663574451\" style=\"background:transparent;color:#ffffff;padding:14px 26px;border-radius:8px;font-weight:700;text-decoration:none;font-size:15px;display:inline-block;border:2px solid #ffffff;\">\ud83d\udcde 1-866-357-4451<\/a>\n      <\/div>\n    <\/div>\n    <div style=\"flex:0 0 240px;text-align:center;\"><img decoding=\"async\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize,to_auto,s_webp:avif\/www.assur360.ca\/wp-content\/uploads\/2024\/02\/courtier-assurance-entreprise-du-quebec-en-ligne.png\" alt=\"Orso, courtier d'assurance entreprise selon activit\u00e9\" style=\"max-width:240px;width:100%;height:auto;display:block;margin:0 auto;filter:drop-shadow(0 6px 16px rgba(16,196,199,0.3));\" loading=\"lazy\" \/><\/div>\n  <\/div>\n<\/div>\n\n<div style=\"background:linear-gradient(135deg,#0d1f2d 0%,#1a3a4a 100%);padding:60px 24px;text-align:center;border-radius:0 0 16px 16px;margin-bottom:40px;\">\n  <p style=\"color:#10c4c7;font-size:14px;font-weight:700;letter-spacing:3px;text-transform:uppercase;margin:0 0 16px;\">QUICK QUOTE<\/p>\n  <h2 style=\"color:#ffffff;font-size:32px;font-weight:800;margin:0 0 20px;line-height:1.3;\"><span class=\"ez-toc-section\" id=\"Hotel-Management-and-Multiple-Risks-Why-Specialty-Insurance-Is-Essential\"><\/span>Hotel Management and Multiple Risks: Why Specialty Insurance Is Essential<span class=\"ez-toc-section-end\"><\/span><\/h2>\n  <p style=\"color:#94a3b8;font-size:16px;margin:0 auto 32px;max-width:700px;line-height:1.6;\">Managing a hotel means welcoming the public 24\/7, managing employees, securing the premises and protecting the property of customers. An error, a disaster or an incident can quickly become costly. <strong>Insurance designed specifically for hotel establishments<\/strong>, offered by <strong>insurance brokers<\/strong>, helps ensure your business continuity, reputation and peace of mind.  <\/p>\n  <div style=\"display:flex;gap:16px;justify-content:center;flex-wrap:wrap;\">\n    <a href=\"https:\/\/www.assur360.ca\/en\/business-insurance-quote-5\/\" style=\"display:inline-block;background:#10c4c7;color:#ffffff;padding:14px 32px;border-radius:8px;text-decoration:none;font-weight:700;font-size:16px;\">Get my free<\/a>\n quote<a href=\"tel:+18663574451\" style=\"display:inline-block;background:transparent;color:#ffffff;padding:14px 32px;border-radius:8px;text-decoration:none;font-weight:700;font-size:16px;border:2px solid #ffffff;\">1-866-357-4451<\/a>    \n  <\/div>\n<\/div>\n\n<figure class=\"wp-block-image size-large\"><img alt=\"Un b\u00e2timent moderne aux grandes fen\u00eatres teint\u00e9es de bleu et au toit plat arbore un panneau \u00ab\u00a0HOTEL\u00a0\u00bb audacieux sur un ciel d\u00e9gag\u00e9\u00a0: id\u00e9al pour ceux qui recherchent l&#039;Assurance H\u00f4tels ou une offre personnalis\u00e9e. Sa fa\u00e7ade contemporaine se distingue par ses lignes \u00e9pur\u00e9es.\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize,to_auto,s_webp:avif\/www.assur360.ca\/wp-content\/uploads\/2025\/05\/Assurance-Hotel-.png\" alt=\"\" class=\"wp-image-18530\"  sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Why a specific insurance for hotels?<\/h3>\n\n<ul class=\"wp-block-list\">\n<li>High traffic volume: More visitors = more risk of damage or accidents.<\/li>\n\n\n\n<li>Responsibility to guests: You are legally responsible for the property and safety of your guests.<\/li>\n\n\n\n<li>Risk of fire, water damage, theft: Hotel infrastructures are exposed to many disasters.<\/li>\n\n\n\n<li>Expensive equipment: Industrial kitchens, bedding, security systems, etc.<\/li>\n\n\n\n<li>Large staff: Work accidents, service errors or conflicts can occur.<\/li>\n<\/ul>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Essential guarantees for a hotel<\/h3>\n\n<figure class=\"wp-block-table\"><table class=\"has-ast-global-color-0-background-color has-background has-fixed-layout\"><thead><tr><th><strong>Recommended Warranty<\/strong><\/th><th><strong>Description<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Commercial General Liability<\/td><td>Protects against injury or damage to a customer.<\/td><\/tr><tr><td>Commercial Property Insurance<\/td><td>Covers the building, furniture, equipment and d\u00e9cor.<\/td><\/tr><tr><td>Business interruption<\/td><td>Covers loss of income in the event of a temporary closure.<\/td><\/tr><tr><td>Employee liability<\/td><td>Protects the hotel against the faults or errors of its employees.<\/td><\/tr><tr><td>Insurance against damage to customers&#8217; property<\/td><td>Protects against loss or theft of customers&#8217; personal belongings.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Why compare hotel insurance?<\/h3>\n\n<ul class=\"wp-block-list\">\n<li><strong>Targeted offers<\/strong> : A hotel&#8217;s insurance needs are specific and complex.<\/li>\n\n\n\n<li><strong>Optimize your costs<\/strong> : Access the best premiums for the benefits you need.<\/li>\n\n\n\n<li><strong>Time saving<\/strong> : Compare multiple insurers in minutes.<\/li>\n\n\n\n<li><strong>Expert support<\/strong> : Our broker partners are familiar with the realities of the hotel industry.<\/li>\n\n\n\n<li><strong>Clarity of contracts<\/strong> : Easily compare exclusions, ceilings and deductibles.<\/li>\n<\/ul>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Specialized-insurers-for-hotels\"><\/span>Specialized insurers for hotels<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<figure class=\"wp-block-table\"><table class=\"has-ast-global-color-0-background-color has-background has-fixed-layout\"><thead><tr><th><strong>Insurer<\/strong><\/th><th><strong>Overall satisfaction<\/strong><\/th><th><strong>Hospitality Expertise<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Intact Insurance<\/td><td>\u2b50\u2b50\u2b50\u2b50\u2606<\/td><td>\u2b50\u2b50\u2b50\u2b50\u2606<\/td><\/tr><tr><td>Aviva insurance<\/td><td>\u2b50\u2b50\u2b50\u2b50\u2606<\/td><td>\u2b50\u2b50\u2b50\u2b50\u2b50<\/td><\/tr><tr><td>The Unique<\/td><td>\u2b50\u2b50\u2b50\u2b50\u2606<\/td><td>\u2b50\u2b50\u2b50\u2b50\u2606<\/td><\/tr><tr><td>The Capital\/Beneva<\/td><td>\u2b50\u2b50\u2b50\u2b50\u2606<\/td><td>\u2b50\u2b50\u2b50\u2b50\u2606<\/td><\/tr><tr><td>Travelers Canada<\/td><td>\u2b50\u2b50\u2b50\u2b50\u2606<\/td><td>\u2b50\u2b50\u2b50\u2b50\u2606<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-wpseopress-faq-block-v2 is-layout-flow wp-block-wpseopress-faq-block-v2-is-layout-flow\">\n<details id=\"une-assurance-est-elle-obligatoire-pour-exploiter-un-hotel-au-quebec\" class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Is insurance required to operate a hotel in Quebec?<\/summary>\n<p>Yes. Civil liability insurance is mandatory, or even strongly recommended, depending on the municipality and the accommodation standards. <\/p>\n<\/details>\n\n\n\n<details id=\"que-couvre-une-assurance-hoteliere\" class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Que couvre une assurance h\u00f4teli\u00e8re ?<br \/><\/summary>\n<p>It can cover claims, civil liability, operating losses, equipment, etc.<\/p>\n<\/details>\n\n\n\n<details id=\"est-ce-quune-assurance-habitation-peut-couvrir-mon-hotel\" class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Est-ce qu\u2019une assurance habitation peut couvrir mon h\u00f4tel ?<br \/><\/summary>\n<p>No, home insurance does not cover hotel-specific business risks. Trade insurance is essential. <\/p>\n<\/details>\n<script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"FAQPage\",\"url\":\"https:\/\/www.assur360.ca\/assurance-entreprise\/assurance-hotels\/\",\"@id\":\"https:\/\/www.assur360.ca\/assurance-entreprise\/assurance-hotels\/\",\"mainEntity\":[{\"@type\":\"Question\",\"url\":\"https:\/\/www.assur360.ca\/assurance-entreprise\/assurance-hotels\/#une-assurance-est-elle-obligatoire-pour-exploiter-un-hotel-au-quebec\",\"name\":\"Une assurance est-elle obligatoire pour exploiter un h\u00f4tel au Qu\u00e9bec?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"&lt;p>Oui. Une assurance responsabilit\u00e9 civile est obligatoire, voire fortement recommand\u00e9e, selon les municipalit\u00e9s et les normes d\u2019h\u00e9bergement.&lt;\/p>\"}},{\"@type\":\"Question\",\"url\":\"https:\/\/www.assur360.ca\/assurance-entreprise\/assurance-hotels\/#que-couvre-une-assurance-hoteliere\",\"name\":\"Que couvre une assurance h\u00f4teli\u00e8re ?\\n\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"&lt;p>Elle peut couvrir les sinistres, la responsabilit\u00e9 civile, les pertes d\u2019exploitation, les \u00e9quipements, etc.&lt;\/p>\"}},{\"@type\":\"Question\",\"url\":\"https:\/\/www.assur360.ca\/assurance-entreprise\/assurance-hotels\/#est-ce-quune-assurance-habitation-peut-couvrir-mon-hotel\",\"name\":\"Est-ce qu\u2019une assurance habitation peut couvrir mon h\u00f4tel ?\\n\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"&lt;p>Non, les assurances habitation ne couvrent pas les risques commerciaux sp\u00e9cifiques aux h\u00f4tels. Une assurance commerciale est essentielle.&lt;\/p>\"}}]}<\/script><\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\" id=\"soumission\"><span class=\"ez-toc-section\" id=\"Request-your-quick-and-free-quote\"><\/span>Request your quick and free quote<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class='fluentform ff-default fluentform_wrapper_31 ffs_custom_wrap'><form data-form_id=\"31\" id=\"fluentform_31\" class=\"frm-fluent-form fluent_form_31 ff-el-form-top ff_form_instance_31_1 ff-form-loading ff-form-has-steps ffs_custom\" data-form_instance=\"ff_form_instance_31_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Soumission entreprise (#3)<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='20097' \/><input type=\"hidden\" id=\"_fluentform_31_fluentformnonce\" name=\"_fluentform_31_fluentformnonce\" value=\"b2c8b7da7d\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/20097\" \/><div class='ff-step-container' data-name=\"step_start-31_5\" data-disable_auto_focus=\"no\" data-enable_auto_slider=\"no\" data-enable_step_data_persistency=\"no\" data-enable_step_page_resume=\"no\" data-animation_type=\"slide\" ><div class='ff-step-header'><ul class='ff-step-titles'><li class='ff_active'><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><li><span><\/span><\/li><\/ul><\/div><span class='ff_step_start'><\/span><div class='ff-step-body'><div class=\"fluentform-step active\" data-name=\"step_start-31_5\" data-disable_auto_focus=\"no\" data-enable_auto_slider=\"no\" data-enable_step_data_persistency=\"no\" data-enable_step_page_resume=\"no\" data-animation_type=\"slide\" ><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group  ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_31_names_first_name_' id='label_ff_31_names_first_name_' >Pr\u00e9nom<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_31_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Pr\u00e9nom\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group  ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_31_names_last_name_' id='label_ff_31_names_last_name_' >Nom de famille<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_31_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Nom de famille\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_31_input_text' id='label_ff_31_input_text' aria-label=\"Nom de l&#039;entreprise\">Nom de l'entreprise<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" data-name=\"input_text\" id=\"ff_31_input_text\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_31_dropdown' id='label_ff_31_dropdown' aria-label=\"Secteur d&#039;activit\u00e9\">Secteur d'activit\u00e9<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown\" id=\"ff_31_dropdown\" class=\"ff-el-form-control\" data-name=\"dropdown\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_31_dropdown\"><option value=\"\">- S\u00e9lectionner -<\/option><option value=\"Entreprises de services professionnels\"  >Entreprises de services professionnels<\/option><option value=\"Entrepreneurs\"  >Entrepreneurs<\/option><option value=\"Commerce de d\u00e9tail et automobile\"  >Commerce de d\u00e9tail et automobile<\/option><option value=\"Immobilier\"  >Immobilier<\/option><option value=\"Restauration et h\u00f4tellerie\"  >Restauration et h\u00f4tellerie<\/option><option value=\"Services de sant\u00e9\"  >Services de sant\u00e9<\/option><option value=\"Fabrication et transformation\"  >Fabrication et transformation<\/option><option value=\"Grossistes\"  >Grossistes<\/option><option value=\"Entreposage\"  >Entreposage<\/option><option value=\"\u00c9nergie\"  >\u00c9nergie<\/option><option value=\"Autres secteur\"  >Autres secteur<\/option><\/select><\/div><\/div><div class='ff-el-group has-conditions'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_31_preciser_secteur' id='label_ff_31_preciser_secteur' aria-label=\"Pr\u00e9cisez votre activit\u00e9\">Pr\u00e9cisez votre activit\u00e9<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"preciser_secteur\" id=\"ff_31_preciser_secteur\" class=\"ff-el-form-control\" placeholder=\"D\u00e9crivez votre activit\u00e9 (secteur, type de produits\/services, etc.)\" data-name=\"preciser_secteur\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Pr\u00e9c\u00e9dent'>Pr\u00e9c\u00e9dent<\/button><button style='float: right;'  type='button' data-action='next' class='ff-float-right ff-btn ff-btn-next ff-btn-secondary' aria-label='Suivant'>Suivant<\/button><\/div><\/div><div style='display: none;' class=\" fluentform-step\" data-name=\"form_step-31_1\" ><div class=\"ff-name-address-wrapper fluent-address\" data-type=\"address-element\" data-name=\"address_1\" ><div class='ff-el-input--label'><label aria-label=\"Adresse\">Adresse<\/label><\/div><div class='ff-el-input--content'><div class='ff-t-container'><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_31_address_1_address_line_1_' id='label_ff_31_address_1_address_line_1_' aria-label=\"Adresse ligne 1\">Adresse ligne 1<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"address_1[address_line_1]\" id=\"ff_31_address_1_address_line_1_\" class=\"ff-el-form-control\" placeholder=\"Adresse ligne 1\" data-key_name=\"address_line_1\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_31_address_1_city_' id='label_ff_31_address_1_city_' aria-label=\"Ville\">Ville<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"address_1[city]\" id=\"ff_31_address_1_city_\" class=\"ff-el-form-control\" placeholder=\"Ville\" data-key_name=\"city\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><\/div><div class='ff-t-container'><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_31_address_1_state_' id='label_ff_31_address_1_state_' aria-label=\"Province\">Province<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"address_1[state]\" id=\"ff_31_address_1_state_\" class=\"ff-el-form-control\" placeholder=\"Qu\u00e9bec seulement\" data-key_name=\"state\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_31_address_1_zip_' id='label_ff_31_address_1_zip_' aria-label=\"Code postal\">Code postal<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"address_1[zip]\" id=\"ff_31_address_1_zip_\" class=\"ff-el-form-control\" placeholder=\"Code Postal\" data-key_name=\"zip\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_31_phone' id='label_ff_31_phone' aria-label=\"T\u00e9l\u00e9phone\/mobile\">T\u00e9l\u00e9phone\/mobile<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone ff_el_with_extended_validation\" value=\"###-###-####\" type=\"tel\" data-name=\"phone\" id=\"ff_31_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=true><\/div><\/div><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Pr\u00e9c\u00e9dent'>Pr\u00e9c\u00e9dent<\/button><button style='float: right;'  type='button' data-action='next' class='ff-float-right ff-btn ff-btn-next ff-btn-secondary' aria-label='Suivant'>Suivant<\/button><\/div><\/div><div style='display: none;' class=\" fluentform-step\" data-name=\"form_step-31_2\" ><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_31_numeric-field' id='label_ff_31_numeric-field' aria-label=\"Ann\u00e9e de cr\u00e9ation de l\u2019entreprise\">Ann\u00e9e de cr\u00e9ation de l\u2019entreprise<\/label><\/div><div class='ff-el-input--content'><input type=\"number\" name=\"numeric-field\" id=\"ff_31_numeric-field\" class=\"ff-el-form-control\" placeholder=\"2023\" data-name=\"numeric-field\" inputmode=\"numeric\" step=\"any\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_31_numeric-field_1' id='label_ff_31_numeric-field_1' aria-label=\"Nombre d&#039;ann\u00e9es d\u2019exp\u00e9rience dans le domaine\">Nombre d'ann\u00e9es d\u2019exp\u00e9rience dans le domaine<\/label><\/div><div class='ff-el-input--content'><input type=\"number\" name=\"numeric-field_1\" id=\"ff_31_numeric-field_1\" class=\"ff-el-form-control\" placeholder=\"1\" data-name=\"numeric-field_1\" inputmode=\"numeric\" step=\"any\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_31_datetime' id='label_ff_31_datetime' aria-label=\"Date \u00e9ch\u00e9ance du contrat\">Date \u00e9ch\u00e9ance du contrat <\/label><\/div><div class='ff-el-input--content'><input  aria-label='Date \u00e9ch\u00e9ance du contrat  Use arrow keys to navigate dates. Press enter to select a date.'  aria-haspopup='dialog' data-type-datepicker data-format='d\/m\/Y' type=\"text\" name=\"datetime\" id=\"ff_31_datetime\" class=\"ff-el-form-control ff-el-datepicker\" data-name=\"datetime\"  aria-invalid='false' aria-required=false><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_31_multi_select' id='label_ff_31_multi_select' aria-label=\"Protection requise\">Protection requise<\/label><\/div><div class='ff-el-input--content'><select name=\"multi_select[]\" id=\"ff_31_multi_select\" class=\"ff-el-form-control  ff_has_multi_select\" multiple=\"1\" data-name=\"multi_select\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"false\" aria-labelledby=\"label_ff_31_multi_select\"><option value=\"B\u00e2timent\"  >B\u00e2timent<\/option><option value=\"Contenu\"  >Contenu<\/option><option value=\"Responsabilit\u00e9 civile\"  >Responsabilit\u00e9 civile<\/option><option value=\"V\u00e9hicule\"  >V\u00e9hicule<\/option><option value=\"Assurance chantier ou\/et Warp up\"  >Assurance chantier ou\/et Warp up<\/option><option value=\"Perte de revenu\"  >Perte de revenu<\/option><option value=\"Cyber-risques\"  >Cyber-risques<\/option><\/select><\/div><\/div><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Pr\u00e9c\u00e9dent'>Pr\u00e9c\u00e9dent<\/button><button style='float: right;'  type='button' data-action='next' class='ff-float-right ff-btn ff-btn-next ff-btn-secondary' aria-label='Suivant'>Suivant<\/button><\/div><\/div><div style='display: none;' class=\" fluentform-step\" data-name=\"form_step-31_3\" ><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"Consentez-vous \u00e0 une v\u00e9rification de cr\u00e9dit?\">Consentez-vous \u00e0 une v\u00e9rification de cr\u00e9dit?<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='input_radio_5df3bf59048721b5a994ec87a492de00'><input  type=\"radio\" name=\"input_radio\" data-name=\"input_radio\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"Oui\"  id='input_radio_5df3bf59048721b5a994ec87a492de00' aria-label='Oui' aria-invalid='false' aria-required=false> <span>Oui<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='input_radio_e0768c400b94e817c7bb8c7702d49786'><input  type=\"radio\" name=\"input_radio\" data-name=\"input_radio\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"Non\"  id='input_radio_e0768c400b94e817c7bb8c7702d49786' aria-label='Non' aria-invalid='false' aria-required=false> <span>Non<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_31_numeric-field_2' id='label_ff_31_numeric-field_2' aria-label=\"Recettes totales annuel (revenus)\">Recettes totales annuel (revenus)<\/label><\/div><div class='ff-el-input--content'><input type=\"number\" name=\"numeric-field_2\" id=\"ff_31_numeric-field_2\" class=\"ff-el-form-control\" placeholder=\"$\" data-name=\"numeric-field_2\" inputmode=\"numeric\" step=\"any\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_31_input_text_1' id='label_ff_31_input_text_1' aria-label=\"Assureur actuel ou ant\u00e9rieur\">Assureur actuel ou ant\u00e9rieur<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_1\" class=\"ff-el-form-control\" data-name=\"input_text_1\" id=\"ff_31_input_text_1\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Pr\u00e9c\u00e9dent'>Pr\u00e9c\u00e9dent<\/button><button style='float: right;'  type='button' data-action='next' class='ff-float-right ff-btn ff-btn-next ff-btn-secondary' aria-label='Suivant'>Suivant<\/button><\/div><\/div><div style='display: none;' class=\" fluentform-step\" data-name=\"form_step-31_4\" ><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_31_email' id='label_ff_31_email' aria-label=\"Courriel\">Courriel<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_31_email\" class=\"ff-el-form-control\" placeholder=\"Email\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label   aria-label=\"Les informations recueillies \u00e0 cette section nous permettent entre autres d\u2019effectuer une pr\u00e9qualification concernant vos besoins en assurance et potentiellement vous proposer une soumission d\u2019assurance. Les informations fournies sont conserv\u00e9es de fa\u00e7on \u00e0 r\u00e9pondre aux exigences l\u00e9gislatives et r\u00e8glementaires. Par ailleurs, en remplissant le formulaire, vous consentez \u00e0 ce que nous utilisions, communiquions ou partagions \u00e0 l\u2019interne et \u00e0 l\u2019externe (notamment \u00e0 des cabinets partenaires et\/ou assureurs) et que nous conservions ces informations.\">Les informations recueillies \u00e0 cette section nous permettent entre autres d\u2019effectuer une pr\u00e9qualification concernant vos besoins en assurance et potentiellement vous proposer une soumission d\u2019assurance. Les informations fournies sont conserv\u00e9es de fa\u00e7on \u00e0 r\u00e9pondre aux exigences l\u00e9gislatives et r\u00e8glementaires. Par ailleurs, en remplissant le formulaire, vous consentez \u00e0 ce que nous utilisions, communiquions ou partagions \u00e0 l\u2019interne et \u00e0 l\u2019externe (notamment \u00e0 des cabinets partenaires et\/ou assureurs) et que nous conservions ces informations.<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_587d1cb6560cd21fa3fe83714cdfe3b1'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"J&#039;accepte\"  id='checkbox_587d1cb6560cd21fa3fe83714cdfe3b1' aria-label='J&#039;accepte' aria-invalid='false' aria-required=true> <span>J'accepte<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group ff-el-form-hide_label'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"Je d\u00e9sire m&#039;abonner \u00e0 l&#039;infolettre d&#039;Assur360 pour ses concours, promotions et informations\">Je d\u00e9sire m'abonner \u00e0 l'infolettre d'Assur360 pour ses concours, promotions et informations<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_1_ba8efbc4b7b7c970cf8e880298879a4a'><input  type=\"checkbox\" name=\"checkbox_1[]\" data-name=\"checkbox_1\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Je d\u00e9sire m&#039;abonner \u00e0 l&#039;infolettre d&#039;Assur360 pour ses concours, promotions et informations\"  id='checkbox_1_ba8efbc4b7b7c970cf8e880298879a4a' aria-label='Je d\u00e9sire m&#039;abonner \u00e0 l&#039;infolettre d&#039;Assur360 pour ses concours, promotions et informations' aria-invalid='false' aria-required=false> <span>Je d\u00e9sire m'abonner \u00e0 l'infolettre d'Assur360 pour ses concours, promotions et informations<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_31_description' id='label_ff_31_description' aria-label=\"Informations additionnels\">Informations additionnels<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"false\" aria-labelledby=\"label_ff_31_description\" name=\"description\" id=\"ff_31_description\" class=\"ff-el-form-control\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div>        <div class=\"ff-step-t-container ff-inner_submit_container ff-column-container ff_columns_total_2\">\n            <div class=\"ff-t-cell ff-t-column-1\"><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Previous'>Previous<\/button><\/div><\/div>\n            <div class=\"ff-t-cell ff-t-column-2\">\n                <div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\"  aria-label=\"Soumettre la demande\">Soumettre la demande<\/button><\/div>            <\/div>\n        <\/div>\n        <\/div><\/div><\/div>\n        <\/fieldset><\/form><div id='fluentform_31_errors' class='ff-errors-in-stack ff_form_instance_31_1 ff-form-loading_errors ff_form_instance_31_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_31_1 = {\"id\":\"31\",\"ajaxUrl\":\"https:\\\/\\\/www.assur360.ca\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_31_1\",\"form_id_selector\":\"fluentform_31\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"names[last_name]\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"input_text\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"dropdown\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"preciser_secteur\":{\"required\":{\"value\":true,\"message\":\"Veuillez pr\\u00e9ciser votre activit\\u00e9\"}},\"address_1[address_line_1]\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"address_1[address_line_2]\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"address_1[city]\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"address_1[state]\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"address_1[zip]\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"address_1[country]\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"phone\":{\"required\":{\"value\":true,\"message\":\"Ce champ est requis\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"},\"valid_phone_number\":{\"value\":true,\"message\":\"Le num\\u00e9ro de t\\u00e9l\\u00e9phone n'est pas valide\",\"global\":false,\"global_message\":\"Le num\\u00e9ro de t\\u00e9l\\u00e9phone est invalide\"}},\"numeric-field\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"},\"numeric\":{\"value\":true,\"message\":\"Ce champ doit contenir une valeur num\\u00e9rique\",\"global\":false,\"global_message\":\"Ce champ doit contenir une valeur num\\u00e9rique\"},\"min\":{\"value\":\"\",\"message\":\"Valeur minimale est \",\"global\":false,\"global_message\":\"\\u00c9chec de la validation pour la valeur minimale\"},\"max\":{\"value\":\"\",\"message\":\"Valeur maximale est \",\"global\":false,\"global_message\":\"\\u00c9chec de la validation pour la valeur maximale\"},\"digits\":{\"value\":\"\",\"message\":\"Le nombre de chiffres doit \\u00eatre \",\"global\":false,\"global_message\":\"La validation \\u00e9choue pour un nombre limit\\u00e9 de chiffres\"}},\"numeric-field_1\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"},\"numeric\":{\"value\":true,\"message\":\"Ce champ doit contenir une valeur num\\u00e9rique\",\"global\":false,\"global_message\":\"Ce champ doit contenir une valeur num\\u00e9rique\"},\"min\":{\"value\":\"\",\"message\":\"Valeur minimale est \",\"global\":false,\"global_message\":\"\\u00c9chec de la validation pour la valeur minimale\"},\"max\":{\"value\":\"\",\"message\":\"Valeur maximale est \",\"global\":false,\"global_message\":\"\\u00c9chec de la validation pour la valeur maximale\"},\"digits\":{\"value\":\"\",\"message\":\"Le nombre de chiffres doit \\u00eatre \",\"global\":false,\"global_message\":\"La validation \\u00e9choue pour un nombre limit\\u00e9 de chiffres\"}},\"datetime\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"multi_select\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"input_radio\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"numeric-field_2\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"},\"numeric\":{\"value\":true,\"message\":\"Ce champ doit contenir une valeur num\\u00e9rique\",\"global\":false,\"global_message\":\"Ce champ doit contenir une valeur num\\u00e9rique\"},\"min\":{\"value\":\"\",\"message\":\"Valeur minimale est \",\"global\":false,\"global_message\":\"\\u00c9chec de la validation pour la valeur minimale\"},\"max\":{\"value\":\"\",\"message\":\"Valeur maximale est \",\"global\":false,\"global_message\":\"\\u00c9chec de la validation pour la valeur maximale\"},\"digits\":{\"value\":\"\",\"message\":\"Le nombre de chiffres doit \\u00eatre \",\"global\":false,\"global_message\":\"La validation \\u00e9choue pour un nombre limit\\u00e9 de chiffres\"}},\"input_text_1\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"},\"email\":{\"value\":true,\"message\":\"Ce champ doit contenir un e-mail valide\",\"global\":false,\"global_message\":\"Ce champ doit contenir un e-mail valide\"}},\"checkbox\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"checkbox_1\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"description\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}}},\"debounce_time\":300,\"conditionals\":{\"preciser_secteur\":{\"type\":\"any\",\"status\":true,\"conditions\":[{\"field\":\"dropdown\",\"value\":\"Autres secteur\",\"operator\":\"=\"}]}}};\n                            <\/script>\n            \n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div style=\"background:linear-gradient(135deg,#0d1f2d 0%,#1a3a4a 100%);padding:48px 24px;text-align:center;max-width:1200px;margin:0 auto;border-radius:16px;\">\n  <p style=\"color:#10c4c7;font-size:14px;font-weight:700;letter-spacing:3px;text-transform:uppercase;margin:0 0 12px;\">COMPARE AND SAVE<\/p>\n  <h2 style=\"color:#ffffff;font-size:28px;font-weight:800;margin:0 0 16px;\"><span class=\"ez-toc-section\" id=\"Protect-your-business-at-the-best-price\"><\/span>Protect your business at the best price<span class=\"ez-toc-section-end\"><\/span><\/h2>\n  <p style=\"color:#94a3b8;font-size:16px;margin:0 0 28px;\">Our AMF-certified brokers compare several insurers to find you the best business coverage.<\/p>\n  <div style=\"display:flex;gap:16px;justify-content:center;flex-wrap:wrap;\">\n    <a href=\"https:\/\/www.assur360.ca\/en\/business-insurance-quote-5\/\" style=\"display:inline-block;background:#10c4c7;color:#ffffff;padding:14px 32px;border-radius:8px;text-decoration:none;font-weight:700;font-size:16px;\">Get my free<\/a>\n quote<a href=\"tel:+18663574451\" style=\"display:inline-block;background:transparent;color:#ffffff;padding:14px 32px;border-radius:8px;text-decoration:none;font-weight:700;font-size:16px;border:2px solid #ffffff;\">1-866-357-4451<\/a>    \n  <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>QUICK QUOTE Hotel Management and Multiple Risks: Why Specialty Insurance Is Essential Managing a hotel means welcoming the public 24\/7, managing employees, [&hellip;]<\/p>\n","protected":false},"author":44,"featured_media":26931,"parent":15787,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Your personalized hotel insurance","_seopress_titles_desc":"Protect your hotel with tailor-made insurance. Compare offers and get a free quote in minutes. ","_seopress_robots_index":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","yasr_pro_reviews_in_comment_enabled":0,"footnotes":""},"class_list":["post-20097","page","type-page","status-publish","has-post-thumbnail","hentry"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/www.assur360.ca\/en\/wp-json\/wp\/v2\/pages\/20097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.assur360.ca\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.assur360.ca\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.assur360.ca\/en\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/www.assur360.ca\/en\/wp-json\/wp\/v2\/comments?post=20097"}],"version-history":[{"count":20,"href":"https:\/\/www.assur360.ca\/en\/wp-json\/wp\/v2\/pages\/20097\/revisions"}],"predecessor-version":[{"id":49610,"href":"https:\/\/www.assur360.ca\/en\/wp-json\/wp\/v2\/pages\/20097\/revisions\/49610"}],"up":[{"embeddable":true,"href":"https:\/\/www.assur360.ca\/en\/wp-json\/wp\/v2\/pages\/15787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.assur360.ca\/en\/wp-json\/wp\/v2\/media\/26931"}],"wp:attachment":[{"href":"https:\/\/www.assur360.ca\/en\/wp-json\/wp\/v2\/media?parent=20097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}